{"id":5870,"date":"2019-12-17T10:35:51","date_gmt":"2019-12-17T09:35:51","guid":{"rendered":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg"},"modified":"2021-07-29T17:27:48","modified_gmt":"2021-07-29T15:27:48","slug":"okmodelexpo2020-2","status":"inherit","type":"attachment","link":"https:\/\/www.veronafiere.it\/en\/calendar\/our-products-in-italy\/okmodelexpo2020-2\/","title":{"rendered":"okmodelexpo2020"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>okmodelexpo2020 - Veronafiere S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"okmodelexpo2020 - Veronafiere S.p.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Veronafiere S.p.A.\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T15:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"188\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\",\"url\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\",\"name\":\"okmodelexpo2020 - Veronafiere S.p.A.\",\"isPartOf\":{\"@id\":\"https:\/\/www.veronafiere.it\/#website\"},\"datePublished\":\"2019-12-17T09:35:51+00:00\",\"dateModified\":\"2021-07-29T15:27:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.veronafiere.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendar\",\"item\":\"https:\/\/www.veronafiere.it\/en\/calendar\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Our products in Italy\",\"item\":\"https:\/\/www.veronafiere.it\/en\/calendar\/our-products-in-italy\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"okmodelexpo2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.veronafiere.it\/#website\",\"url\":\"https:\/\/www.veronafiere.it\/\",\"name\":\"Veronafiere S.p.A.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.veronafiere.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"okmodelexpo2020 - Veronafiere S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg","og_locale":"en_US","og_type":"article","og_title":"okmodelexpo2020 - Veronafiere S.p.A.","og_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg","og_site_name":"Veronafiere S.p.A.","article_modified_time":"2021-07-29T15:27:48+00:00","og_image":[{"width":188,"height":160,"url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg","url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg","name":"okmodelexpo2020 - Veronafiere S.p.A.","isPartOf":{"@id":"https:\/\/www.veronafiere.it\/#website"},"datePublished":"2019-12-17T09:35:51+00:00","dateModified":"2021-07-29T15:27:48+00:00","breadcrumb":{"@id":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veronafiere.it\/"},{"@type":"ListItem","position":2,"name":"Calendar","item":"https:\/\/www.veronafiere.it\/en\/calendar\/"},{"@type":"ListItem","position":3,"name":"Our products in Italy","item":"https:\/\/www.veronafiere.it\/en\/calendar\/our-products-in-italy\/"},{"@type":"ListItem","position":4,"name":"okmodelexpo2020"}]},{"@type":"WebSite","@id":"https:\/\/www.veronafiere.it\/#website","url":"https:\/\/www.veronafiere.it\/","name":"Veronafiere S.p.A.","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veronafiere.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"188\" height=\"160\" src=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":188,"height":160,"file":"2019\/12\/OKmodelexpo2020.jpg","sizes":{"thumbnail":{"file":"OKmodelexpo2020-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020-150x150.jpg"},"full":{"file":"OKmodelexpo2020.jpg","width":188,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":7697,"source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2019\/12\/OKmodelexpo2020.jpg","_links":{"self":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/media\/5870"}],"collection":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/comments?post=5870"}]}}