{"id":7071,"date":"2021-02-03T10:52:24","date_gmt":"2021-02-03T09:52:24","guid":{"rendered":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg"},"modified":"2021-07-29T17:27:47","modified_gmt":"2021-07-29T15:27:47","slug":"oksamgenerico","status":"inherit","type":"attachment","link":"https:\/\/www.veronafiere.it\/en\/calendar\/our-products-in-italy\/oksamgenerico\/","title":{"rendered":"OKsamGenerico"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OKsamGenerico - Veronafiere S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OKsamGenerico - Veronafiere S.p.A.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Veronafiere S.p.A.\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T15:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"340\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg\",\"url\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg\",\"name\":\"OKsamGenerico - Veronafiere S.p.A.\",\"isPartOf\":{\"@id\":\"https:\/\/www.veronafiere.it\/#website\"},\"datePublished\":\"2021-02-03T09:52:24+00:00\",\"dateModified\":\"2021-07-29T15:27:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.veronafiere.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendar\",\"item\":\"https:\/\/www.veronafiere.it\/en\/calendar\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Our products in Italy\",\"item\":\"https:\/\/www.veronafiere.it\/en\/calendar\/our-products-in-italy\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"OKsamGenerico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.veronafiere.it\/#website\",\"url\":\"https:\/\/www.veronafiere.it\/\",\"name\":\"Veronafiere S.p.A.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.veronafiere.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OKsamGenerico - Veronafiere S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg","og_locale":"en_US","og_type":"article","og_title":"OKsamGenerico - Veronafiere S.p.A.","og_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg","og_site_name":"Veronafiere S.p.A.","article_modified_time":"2021-07-29T15:27:47+00:00","og_image":[{"width":340,"height":340,"url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg","url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg","name":"OKsamGenerico - Veronafiere S.p.A.","isPartOf":{"@id":"https:\/\/www.veronafiere.it\/#website"},"datePublished":"2021-02-03T09:52:24+00:00","dateModified":"2021-07-29T15:27:47+00:00","breadcrumb":{"@id":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veronafiere.it\/"},{"@type":"ListItem","position":2,"name":"Calendar","item":"https:\/\/www.veronafiere.it\/en\/calendar\/"},{"@type":"ListItem","position":3,"name":"Our products in Italy","item":"https:\/\/www.veronafiere.it\/en\/calendar\/our-products-in-italy\/"},{"@type":"ListItem","position":4,"name":"OKsamGenerico"}]},{"@type":"WebSite","@id":"https:\/\/www.veronafiere.it\/#website","url":"https:\/\/www.veronafiere.it\/","name":"Veronafiere S.p.A.","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veronafiere.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico-300x300.jpg 300w, https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico-150x150.jpg 150w, https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg 340w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":340,"height":340,"file":"2021\/02\/OKsamGenerico.jpg","sizes":{"medium":{"file":"OKsamGenerico-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico-300x300.jpg"},"thumbnail":{"file":"OKsamGenerico-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico-150x150.jpg"},"full":{"file":"OKsamGenerico.jpg","width":340,"height":340,"mime_type":"image\/jpeg","source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":7697,"source_url":"https:\/\/www.veronafiere.it\/wp-content\/uploads\/2021\/02\/OKsamGenerico.jpg","_links":{"self":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/media\/7071"}],"collection":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/comments?post=7071"}]}}