{"id":2732,"date":"2016-10-21T16:16:28","date_gmt":"2016-10-21T14:16:28","guid":{"rendered":"https:\/\/www.veronafiere.it\/en\/?page_id=2732"},"modified":"2016-10-21T16:16:28","modified_gmt":"2016-10-21T14:16:28","slug":"organizza-da-noi-inglese","status":"publish","type":"page","link":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/","title":{"rendered":"Organizza da noi inglese"},"content":{"rendered":"<p>Organizza da noi inglese<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizza da noi inglese<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Organizza da noi inglese - Veronafiere S.p.A.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organizza da noi inglese - Veronafiere S.p.A.\" \/>\n<meta property=\"og:description\" content=\"Organizza da noi inglese\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/\" \/>\n<meta property=\"og:site_name\" content=\"Veronafiere S.p.A.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/\",\"url\":\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/\",\"name\":\"Organizza da noi inglese - Veronafiere S.p.A.\",\"isPartOf\":{\"@id\":\"https:\/\/www.veronafiere.it\/#website\"},\"datePublished\":\"2016-10-21T14:16:28+00:00\",\"dateModified\":\"2016-10-21T14:16:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.veronafiere.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Organizza da noi inglese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.veronafiere.it\/#website\",\"url\":\"https:\/\/www.veronafiere.it\/\",\"name\":\"Veronafiere S.p.A.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.veronafiere.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Organizza da noi inglese - Veronafiere S.p.A.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/","og_locale":"en_US","og_type":"article","og_title":"Organizza da noi inglese - Veronafiere S.p.A.","og_description":"Organizza da noi inglese","og_url":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/","og_site_name":"Veronafiere S.p.A.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/","url":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/","name":"Organizza da noi inglese - Veronafiere S.p.A.","isPartOf":{"@id":"https:\/\/www.veronafiere.it\/#website"},"datePublished":"2016-10-21T14:16:28+00:00","dateModified":"2016-10-21T14:16:28+00:00","breadcrumb":{"@id":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.veronafiere.it\/en\/organizza-da-noi-inglese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.veronafiere.it\/"},{"@type":"ListItem","position":2,"name":"Organizza da noi inglese"}]},{"@type":"WebSite","@id":"https:\/\/www.veronafiere.it\/#website","url":"https:\/\/www.veronafiere.it\/","name":"Veronafiere S.p.A.","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.veronafiere.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/pages\/2732"}],"collection":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/comments?post=2732"}],"version-history":[{"count":1,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/pages\/2732\/revisions"}],"predecessor-version":[{"id":2733,"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/pages\/2732\/revisions\/2733"}],"wp:attachment":[{"href":"https:\/\/www.veronafiere.it\/en\/wp-json\/wp\/v2\/media?parent=2732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}